{"id":3292,"date":"2025-06-11T08:59:00","date_gmt":"2025-06-11T08:59:00","guid":{"rendered":"https:\/\/outdoormedals.com\/datenschutzbestimmungen\/"},"modified":"2025-06-11T11:08:31","modified_gmt":"2025-06-11T11:08:31","slug":"datenschutzbestimmungen","status":"publish","type":"page","link":"https:\/\/outdoormedals.com\/de\/datenschutzbestimmungen\/","title":{"rendered":"Datenschutzbestimmungen"},"content":{"rendered":"&#13;\n<h2 class=\"wp-block-heading\">Wer wir sind<\/h2>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Unsere Website-Adresse lautet: https:\/\/solutiodesigntestserver.nl\/outdoormedals.<\/p>&#13;\n&#13;\n<h2 class=\"wp-block-heading\">Welche pers\u00f6nlichen Daten wir sammeln und warum wir sie sammeln<\/h2>&#13;\n&#13;\n<h3 class=\"wp-block-heading\">Kommentare<\/h3>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Wenn Besucher Kommentare auf der Website hinterlassen, erfassen wir die im Kommentarformular angezeigten Daten sowie die IP-Adresse und den User-Agent-String des Browsers des Besuchers, um die Spam-Erkennung zu erleichtern.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Eine anonymisierte Zeichenfolge, die aus Ihrer E-Mail-Adresse erstellt wird (auch Hash genannt), kann dem Gravatar-Dienst zur Verf\u00fcgung gestellt werden, um zu sehen, ob Sie ihn verwenden. Die Datenschutzbestimmungen des Gravatar-Dienstes finden Sie hier: https:\/\/automattic.com\/privacy\/. Nach der Genehmigung Ihres Kommentars ist Ihr Profilbild im Zusammenhang mit Ihrem Kommentar \u00f6ffentlich sichtbar.<\/p>&#13;\n&#13;\n<h3 class=\"wp-block-heading\">Medien<\/h3>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Wenn Sie Bilder auf die Website hochladen, sollten Sie es vermeiden, Bilder hochzuladen, die eingebettete Standortdaten (EXIF-GPS) enthalten. Die Besucher der Website k\u00f6nnen alle Standortdaten von den Bildern auf der Website herunterladen und extrahieren.<\/p>&#13;\n&#13;\n<h3 class=\"wp-block-heading\">Cookies<\/h3>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Wenn Sie einen Kommentar auf unserer Website hinterlassen, k\u00f6nnen Sie der Speicherung Ihres Namens, Ihrer E-Mail-Adresse und Ihrer Website in Cookies zustimmen. Diese dienen der Bequemlichkeit, damit Sie Ihre Daten nicht erneut eingeben m\u00fcssen, wenn Sie einen weiteren Kommentar hinterlassen. Diese Kekse sind ein Jahr lang haltbar.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Wenn Sie unsere Anmeldeseite besuchen, setzen wir ein tempor\u00e4res Cookie, um festzustellen, ob Ihr Browser Cookies zul\u00e4sst. Dieses Cookie enth\u00e4lt keine pers\u00f6nlichen Daten und wird gel\u00f6scht, wenn Sie Ihren Browser schlie\u00dfen.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Wenn Sie sich anmelden, legen wir au\u00dferdem mehrere Cookies an, um Ihre Anmeldeinformationen und die Auswahl Ihrer Bildschirmdarstellung zu speichern. Anmelde-Cookies bleiben zwei Tage lang erhalten, Cookies f\u00fcr Bildschirmoptionen ein Jahr lang. Wenn Sie &#8222;Remember Me&#8220; w\u00e4hlen, bleibt Ihr Login zwei Wochen lang erhalten. Wenn Sie sich von Ihrem Konto abmelden, werden die Anmelde-Cookies entfernt.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Wenn Sie einen Artikel bearbeiten oder ver\u00f6ffentlichen, wird ein zus\u00e4tzliches Cookie in Ihrem Browser gespeichert. Dieses Cookie enth\u00e4lt keine pers\u00f6nlichen Daten, sondern zeigt lediglich die Post-ID des Artikels an, den Sie gerade bearbeitet haben. Er verf\u00e4llt nach 1 Tag.<\/p>&#13;\n&#13;\n<h3 class=\"wp-block-heading\">Eingebettete Inhalte von anderen Websites<\/h3>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Die Artikel auf dieser Website k\u00f6nnen eingebettete Inhalte enthalten (z. B. Videos, Bilder, Artikel usw.). Eingebettete Inhalte von anderen Websites verhalten sich genau so, als ob der Besucher die andere Website besucht h\u00e4tte.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Diese Websites k\u00f6nnen Daten \u00fcber Sie sammeln, Cookies verwenden, zus\u00e4tzliche Trackingfunktionen von Dritten einbetten und Ihre Interaktion mit diesen eingebetteten Inhalten \u00fcberwachen, einschlie\u00dflich der Verfolgung Ihrer Interaktion mit den eingebetteten Inhalten, wenn Sie ein Konto haben und auf dieser Website angemeldet sind.<\/p>&#13;\n&#13;\n<h3 class=\"wp-block-heading\">Analytik<\/h3>&#13;\n&#13;\n<h2 class=\"wp-block-heading\">Wie lange wir Ihre Daten aufbewahren<\/h2>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Wenn Sie einen Kommentar hinterlassen, werden der Kommentar und seine Metadaten auf unbestimmte Zeit gespeichert. Auf diese Weise k\u00f6nnen wir Folgekommentare automatisch erkennen und genehmigen, anstatt sie in einer Moderationswarteschlange zu halten.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Bei Nutzern, die sich auf unserer Website registrieren (falls vorhanden), speichern wir auch die pers\u00f6nlichen Daten, die sie in ihrem Nutzerprofil angeben. Alle Nutzer k\u00f6nnen ihre pers\u00f6nlichen Daten jederzeit einsehen, bearbeiten oder l\u00f6schen (nur ihren Benutzernamen k\u00f6nnen sie nicht \u00e4ndern). Auch Website-Administratoren k\u00f6nnen diese Informationen einsehen und bearbeiten.<\/p>&#13;\n&#13;\n<h2 class=\"wp-block-heading\">Welche Rechte Sie an Ihren Daten haben<\/h2>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Wenn Sie ein Konto auf dieser Website haben oder Kommentare hinterlassen haben, k\u00f6nnen Sie eine exportierte Datei mit den personenbezogenen Daten anfordern, die wir \u00fcber Sie gespeichert haben, einschlie\u00dflich der Daten, die Sie uns zur Verf\u00fcgung gestellt haben. Sie k\u00f6nnen auch verlangen, dass wir die \u00fcber Sie gespeicherten personenbezogenen Daten l\u00f6schen. Davon ausgenommen sind Daten, die wir aus verwaltungstechnischen, rechtlichen oder sicherheitsrelevanten Gr\u00fcnden aufbewahren m\u00fcssen.<\/p>&#13;\n&#13;\n<h2 class=\"wp-block-heading\">Wohin wir Ihre Daten senden<\/h2>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Die Kommentare der Besucher k\u00f6nnen durch einen automatischen Spam-Erkennungsdienst \u00fcberpr\u00fcft werden.<\/p>&#13;\n&#13;\n<h3 class=\"wp-block-heading\"><\/h3>&#13;\n","protected":false},"excerpt":{"rendered":"<p>&#13; Wer wir sind &#13; &#13; Unsere Website-Adresse lautet: https:\/\/solutiodesigntestserver.nl\/outdoormedals. &#13; &#13; Welche pers\u00f6nlichen Daten wir sammeln und warum wir sie sammeln &#13; &#13; Kommentare &#13; &#13; Wenn Besucher Kommentare auf der Website hinterlassen, erfassen wir die im Kommentarformular angezeigten Daten sowie die IP-Adresse und den User-Agent-String des Browsers des Besuchers, um die Spam-Erkennung zu [&#8230;]\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3292","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/outdoormedals.com\/de\/wp-json\/wp\/v2\/pages\/3292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/outdoormedals.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/outdoormedals.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/outdoormedals.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/outdoormedals.com\/de\/wp-json\/wp\/v2\/comments?post=3292"}],"version-history":[{"count":1,"href":"https:\/\/outdoormedals.com\/de\/wp-json\/wp\/v2\/pages\/3292\/revisions"}],"predecessor-version":[{"id":3295,"href":"https:\/\/outdoormedals.com\/de\/wp-json\/wp\/v2\/pages\/3292\/revisions\/3295"}],"wp:attachment":[{"href":"https:\/\/outdoormedals.com\/de\/wp-json\/wp\/v2\/media?parent=3292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}